﻿{"id":380,"date":"2022-11-10T12:05:50","date_gmt":"2022-11-10T11:05:50","guid":{"rendered":"https:\/\/delosce.esteri.it\/?page_id=380"},"modified":"2022-11-10T12:06:07","modified_gmt":"2022-11-10T11:06:07","slug":"dalla_rappresentanza","status":"publish","type":"page","link":"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/","title":{"rendered":"Dalla Rappresentanza"},"content":{"rendered":"        <div class=\"row\">\n\t\t\t<!-- Ricerca sedi post -->\n\t\t\t<div class=\"col-12 mt-4\">\n\t\t\t  <div class=\"callout callout-highlight note ricerca-esteri p-4\">\n                    <div class=\"callout-title\">\n                        <svg class=\"icon\">\n                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-search\"><\/use>\n                        <\/svg>Inserisci i parametri di ricerca                    <\/div>\n                    <form id=\"searchFormPost\" name=\"form-search-post\" class=\"form-row align-items-center\" action=\"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/380\/\" method=\"GET\"> \n                        <!-- <div class=\"form-group pt-5\"> -->\n                            <!-- <input type=\"hidden\" id=\"lang\" name=\"lang\" value=\"\"> --> <!-- <\/div> -->\n\n                        <div class=\"it-datepicker-wrapper\">\n                            <div class=\"row\">\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-init\">Dal<\/label>\n                                    <input class=\"form-control\" name=\"date-init\" id=\"date-init\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\"lang=\"en-EN\">  \n                                <\/div>\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-end\">Al<\/label>\n                                    <input class=\"form-control\" name=\"date-end\" id=\"date-end\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"form-group col-md-12 mt-3\">\n                            <label for=\"searchText\">Campo ricerca libera<\/label>\n                            <input type=\"text\" name=\"searchText\" class=\"form-control\" id=\"searchText\" value=\"\">\n                        <\/div>\n                        <div class=\"form-group col-md-4 offset-md-8 text-end\">\n                            <a href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/\" title=\"Form reset\" id=\"resetImput\" class=\"btn btn-outline-primary btn-xs\">Reset<\/a>\n                            <button type=\"submit\" class=\"btn btn-primary btn-xs\">Mostra risultati<\/button>\n                        <\/div>\n                    <\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                    \n            <div class=\"row\">\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 8 Luglio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/07\/avviso-di-assunzione-di-n-1-impiegato-a-con-contratto-a-tempo-indeterminato-2\/\" title=\"Avviso di assunzione di n.1 impiegato\/a con contratto a tempo indeterminato\">Avviso di assunzione di n.1 impiegato\/a con contratto a tempo indeterminato<\/a><\/h5>\n                            <p class=\"card-text\">La Rappresentanza Permanente d\u2019Italia presso le Organizzazioni Internazionali in Vienna ha indetto una procedura di selezione per l\u2019assunzione di un\/a impiegato\/a da adibire ai servizi di assistente amministrativo a tempo indeterminato. Per maggiori informazioni sui requisiti e sulle modalit\u00e0 di presentazione delle candidature si prega di consultare il testo integrale dell\u2019avviso consultabile QUI Il termine [&hellip;]<\/p>\n                                <a title=\"Avviso di assunzione di n.1 impiegato\/a con contratto a tempo indeterminato\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/07\/avviso-di-assunzione-di-n-1-impiegato-a-con-contratto-a-tempo-indeterminato-2\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 4 Giugno 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/06\/conferenza-asiatica-dellosce-a-bangkok-sulle-sfide-transnazionali-della-sicurezza-digitale\/\" title=\"Conferenza asiatica dell\u2019OSCE a Bangkok sulle sfide transnazionali della sicurezza digitale\">Conferenza asiatica dell\u2019OSCE a Bangkok sulle sfide transnazionali della sicurezza digitale<\/a><\/h5>\n                            <p class=\"card-text\">Il 28 e 29 maggio si \u00e8 svolta a Bangkok la Conferenza asiatica dell\u2019OSCE, organizzata dalla Presidenza finlandese del Gruppo dei Partner asiatici per la cooperazione in collaborazione con il Ministero degli Affari Esteri della Thailandia. \u00a0 L\u2019evento ha riunito rappresentanti degli Stati partecipanti e partner dell\u2019OSCE, organizzazioni internazionali e settore privato per discutere delle [&hellip;]<\/p>\n                                <a title=\"Conferenza asiatica dell\u2019OSCE a Bangkok sulle sfide transnazionali della sicurezza digitale\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/06\/conferenza-asiatica-dellosce-a-bangkok-sulle-sfide-transnazionali-della-sicurezza-digitale\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 12 Maggio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/05\/vienna-mostra-fotografica-dedicata-alla-liberta-di-stampa\/\" title=\"Vienna, mostra fotografica dedicata alla libert\u00e0 di stampa\">Vienna, mostra fotografica dedicata alla libert\u00e0 di stampa<\/a><\/h5>\n                            <p class=\"card-text\">Per celebrare la Giornata mondiale per la libert\u00e0 di stampa e la nuova ricorrenza nazionale in memoria dei giornalisti uccisi nello svolgimento della loro professione, istituita dal Parlamento italiano, la Rappresentanza Permanente d\u2019Italia presso l\u2019OSCE, in cooperazione con ANSA, ha inaugurato oggi a Vienna la mostra fotografica \u201cSafeguarding press freedom: protecting journalists, defending democracy\u201d, dedicata [&hellip;]<\/p>\n                                <a title=\"Vienna, mostra fotografica dedicata alla libert\u00e0 di stampa\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/05\/vienna-mostra-fotografica-dedicata-alla-liberta-di-stampa\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 7 Maggio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/05\/a-ginevra-conferenza-internazionale-osce-sulle-nuove-tecnologie\/\" title=\"A Ginevra Conferenza internazionale OSCE sulle nuove tecnologie\">A Ginevra Conferenza internazionale OSCE sulle nuove tecnologie<\/a><\/h5>\n                            <p class=\"card-text\">Si \u00e8 aperta oggi a Ginevra, nell\u2019ambito della Presidenza svizzera dell\u2019OSCE 2026, la conferenza internazionale dal titolo \u201cAnticipating technologies \u2013 for a safe and humane future\u201d, dedicata all\u2019impatto delle tecnologie emergenti sulla sicurezza, la stabilit\u00e0 e la cooperazione nello spazio OSCE. L\u2019iniziativa riunisce rappresentanti degli Stati partecipanti, organizzazioni internazionali, comunit\u00e0 scientifica e settore privato presso [&hellip;]<\/p>\n                                <a title=\"A Ginevra Conferenza internazionale OSCE sulle nuove tecnologie\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/05\/a-ginevra-conferenza-internazionale-osce-sulle-nuove-tecnologie\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 20 Marzo 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/03\/approvazione-del-bilancio-unificato-dellosce-per-il-2026\/\" title=\"Approvazione del bilancio unificato dell\u2019OSCE per il 2026\">Approvazione del bilancio unificato dell\u2019OSCE per il 2026<\/a><\/h5>\n                            <p class=\"card-text\">Gli Stati partecipanti dell\u2019OSCE hanno approvato lo scorso 19 marzo la proposta di Bilancio Unificato per il 2026 presentata dalla Presidenza in esercizio svizzera, ponendo cos\u00ec fine alla situazione di stallo in cui l\u2019organizzazione si trovava ad operare dal 2022. L&#8217;adozione del bilancio fa seguito ad ampie consultazioni tra gli Stati partecipanti in sede di [&hellip;]<\/p>\n                                <a title=\"Approvazione del bilancio unificato dell\u2019OSCE per il 2026\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/03\/approvazione-del-bilancio-unificato-dellosce-per-il-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 4 Marzo 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/03\/avviso-di-assunzione-ambasciata-ditalia-a-vienna\/\" title=\"Avviso di assunzione &#8211; Ambasciata d&#8217;Italia a Vienna\">Avviso di assunzione &#8211; Ambasciata d&#8217;Italia a Vienna<\/a><\/h5>\n                            <p class=\"card-text\">L&#8217;Ambasciata d&#8217;Italia a Vienna rende noto che \u00e8 indetta una procedura di selezione per l\u2019assunzione a tempo determinato\u00a0di un\u2019unit\u00e0 di personale nella categoria\u00a0\u201cAssistente Amministrativo a contratto\u201d . Le domande di ammissione dovranno pervenire entro e non oltre il 16.03.2026. Per maggiori informazioni consultare l&#8217; Avviso di assunzione di un impiegato\/a a contratto temporaneo (scadenza per [&hellip;]<\/p>\n                                <a title=\"Avviso di assunzione &#8211; Ambasciata d&#8217;Italia a Vienna\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/03\/avviso-di-assunzione-ambasciata-ditalia-a-vienna\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 25 Febbraio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/consiglio-permanente-in-formato-rinforzato-in-occasione-del-quarto-anniversario-dellinvasione-russa-dellucraina\/\" title=\"Consiglio Permanente in formato rinforzato in occasione del quarto anniversario dell&#8217;invasione russa dell&#8217;Ucraina\">Consiglio Permanente in formato rinforzato in occasione del quarto anniversario dell&#8217;invasione russa dell&#8217;Ucraina<\/a><\/h5>\n                            <p class=\"card-text\">Il Rappresentante Permanente d\u2019Italia presso l\u2019OSCE a Vienna, Amb. Andrea Cascone, \u00e8 intervenuto ad una riunione in formato rinforzato del Consiglio permanente dell&#8217;OSCE, organizzata dalla Presidenza in esercizio della Svizzera in occasione del quarto anniversario dell&#8217;invasione russa dell\u2019Ucraina. Leggi qui il testo integrale dell\u2019intervento italiano. &nbsp;<\/p>\n                                <a title=\"Consiglio Permanente in formato rinforzato in occasione del quarto anniversario dell&#8217;invasione russa dell&#8217;Ucraina\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/consiglio-permanente-in-formato-rinforzato-in-occasione-del-quarto-anniversario-dellinvasione-russa-dellucraina\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 10 Febbraio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/litalia-partecipa-alla-conferenza-osce-sulla-lotta-allantisemitismo-a-san-gallo\/\" title=\"L\u2019Italia partecipa alla Conferenza OSCE sulla lotta all\u2019antisemitismo a San Gallo\">L\u2019Italia partecipa alla Conferenza OSCE sulla lotta all\u2019antisemitismo a San Gallo<\/a><\/h5>\n                            <p class=\"card-text\">Si \u00e8 tenuta a San Gallo, il 9 e 10 febbraio scorsi, la Conferenza OSCE sulla lotta all\u2019antisemitismo: primo evento di alto livello nel programma della Presidenza svizzera dell\u2019Organizzazione per la Sicurezza e la Cooperazione in Europa (OSCE). Vi hanno preso parte, per l\u2019Italia, il Coordinatore Nazionale per la lotta contro l\u2019antisemitismo, Gen. Pasquale Angelosanto, [&hellip;]<\/p>\n                                <a title=\"L\u2019Italia partecipa alla Conferenza OSCE sulla lotta all\u2019antisemitismo a San Gallo\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/litalia-partecipa-alla-conferenza-osce-sulla-lotta-allantisemitismo-a-san-gallo\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 3 Febbraio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/avviso-di-assunzione-di-un-a-impiegato-a-a-contratto\/\" title=\"Avviso di assunzione di un\/a impiegato\/a a contratto\">Avviso di assunzione di un\/a impiegato\/a a contratto<\/a><\/h5>\n                            <p class=\"card-text\">La Rappresentanza Permanente d&#8217;Italia presso le Organizzazioni Internazionali in Vienna ha indetto una procedura di selezione per l\u2019assunzione di un\/a impiegato\/a da adibire ai servizi di assistente amministrativo a tempo determinato. Per maggiori informazioni sui requisiti e sulle modalit\u00e0 di presentazione delle candidature si prega di consultare il testo integrale dell&#8217;avviso consultabile qui. Il termine [&hellip;]<\/p>\n                                <a title=\"Avviso di assunzione di un\/a impiegato\/a a contratto\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/avviso-di-assunzione-di-un-a-impiegato-a-a-contratto\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 3 Febbraio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/5209\/\" title=\"\u201cSounds for Peace\u201d \u2013 Il Requiem di Verdi al Musikverein per la solidariet\u00e0\">\u201cSounds for Peace\u201d \u2013 Il Requiem di Verdi al Musikverein per la solidariet\u00e0<\/a><\/h5>\n                            <p class=\"card-text\">Grande partecipazione di pubblico al Musikverein di Vienna per il concerto di beneficenza \u201cSounds for Peace\u201d, promosso dall\u2019Ambasciata d\u2019Italia a Vienna, dalla Rappresentanza Permanente d\u2019Italia presso le Organizzazioni Internazionali, dalla Rappresentanza Permanente presso l\u2019OSCE e dall\u2019Istituto Italiano di Cultura, in collaborazione con l\u2019Universit\u00e0 di Vienna. Protagonisti della serata l\u2019Orchestra e il Coro dell\u2019Ateneo viennese, diretti [&hellip;]<\/p>\n                                <a title=\"\u201cSounds for Peace\u201d \u2013 Il Requiem di Verdi al Musikverein per la solidariet\u00e0\" class=\"read-more\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/news\/dalla_rappresentanza\/2026\/02\/5209\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n            \n            <div class=\"col-md-12 mt-4 pb-4\">\n                <nav class=\"navigation col-md-12\" aria-label=\"Navigation\">\n                    <h2 class=\"screen-reader-text visually-hidden\">Paginazione<\/h2>\n                    <div class=\"nav-links\">\n                    <span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/380\/?pag=2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/380\/?pag=3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/380\/?pag=28\">28<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/380\/?pag=2\"><svg class=\"icon icon-primary\"><use xlink:href=\"https:\/\/delegazioneosce.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-chevron-right\"><\/use><\/svg>\n                                    <span class=\"visually-hidden\">Pagina successiva<\/span><\/a>                    <\/div>\n                <\/nav>\n            <\/div>   <!--.col-md-12 -->\n              <\/div><!--.row -->\n              \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":19,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-380","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=380"}],"version-history":[{"count":0,"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/380\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/pages\/19"}],"wp:attachment":[{"href":"https:\/\/delegazioneosce.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}